{"id":4829,"date":"2025-02-20T13:31:17","date_gmt":"2025-02-20T05:31:17","guid":{"rendered":"https:\/\/rippa-china.com\/?p=4829"},"modified":"2025-05-21T13:55:10","modified_gmt":"2025-05-21T05:55:10","slug":"1-2-tons-chinese-mini-excavator","status":"publish","type":"post","link":"http:\/\/www.rippa-china.com\/es\/1-2-tons-chinese-mini-excavator.html","title":{"rendered":"Miniexcavadora china de 1,4 toneladas"},"content":{"rendered":"<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4833\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/500-1.jpg\" width=\"500\" height=\"500\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/500-1.jpg 500w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/500-1-300x300.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/500-1-150x150.jpg 150w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/500-1-12x12.jpg 12w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Product Details: R12-2 ECO Mini <span class='wp_keywordlink'><a href=\"http:\/\/www.rippa-china.com\/es\/\" title=\"excavadora\" target=\"_blank\">excavadora<\/a><\/span> by RIPPA<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Introducing the R12-2 ECO mini <span class='wp_keywordlink'><a href=\"http:\/\/www.rippa-china.com\/es\/\" title=\"excavadora\" target=\"_blank\">excavadora<\/a><\/span>, a top-selling model from RIPPA, a renowned brand by Shandong RIPPA\u00a0 Machinery Import &amp; Export Co., Ltd. This robust yet compact excavator is designed to meet the needs of various construction and excavation projects.<\/span><\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4830\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/1-2.jpg\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/1-2.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/1-2-300x300.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/1-2-150x150.jpg 150w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/1-2-768x768.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/1-2-12x12.jpg 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/> <img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4831\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/2-1.jpg\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/2-1.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/2-1-300x300.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/2-1-150x150.jpg 150w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/2-1-768x768.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/2-1-12x12.jpg 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/> <img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4832\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/6-2.jpg\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/6-2.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/6-2-300x300.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/6-2-150x150.jpg 150w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/6-2-768x768.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/6-2-12x12.jpg 12w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4841\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/R12-2-Eco\u5305\u7edc\u56fe-Model.jpg\" width=\"1000\" height=\"708\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/R12-2-Eco\u5305\u7edc\u56fe-Model.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/R12-2-Eco\u5305\u7edc\u56fe-Model-300x212.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/R12-2-Eco\u5305\u7edc\u56fe-Model-768x544.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/R12-2-Eco\u5305\u7edc\u56fe-Model-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Especificaciones principales:<\/span><\/p>\n<ul>\n<li><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Tonelaje: 1,2 toneladas<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Motor: Motor diesel Kubota con bajo consumo de combustible, ruido y vibraciones.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Caracter\u00edsticas destacadas:<\/span><\/p>\n<ul>\n<li><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">F\u00e1cil extracci\u00f3n del techo: Perfecto para trabajar en espacios reducidos, el techo puede retirarse r\u00e1pidamente para aumentar la maniobrabilidad.<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Funcionamiento piloto estable: La excavadora ofrece un funcionamiento suave y estable, lo que garantiza la eficiencia energ\u00e9tica y reduce la fatiga de los operadores.<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Gran capacidad de la cuchara: Con una generosa capacidad de la cuchara, la eficiencia de la excavaci\u00f3n se mejora significativamente, reduciendo la necesidad de m\u00faltiples viajes.<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Oscilaci\u00f3n lateral de la pluma: Ideal para aplicaciones que requieren gran precisi\u00f3n y sensibilidad, la capacidad de giro lateral de la pluma garantiza una excavaci\u00f3n precisa.<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Orugas retr\u00e1ctiles: Las orugas pueden retraerse, lo que hace que la excavadora sea adecuada para espacios estrechos y f\u00e1cil de transportar.<\/span><\/li>\n<li><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">Cubierta protectora integrada: Una cubierta protectora trasera abatible proporciona un c\u00f3modo acceso para el mantenimiento y las reparaciones del motor.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 14pt;\">La miniexcavadora R12-2 ECO cuenta con la certificaci\u00f3n CE, lo que garantiza el cumplimiento de las normas europeas de seguridad y medio ambiente. Su versatilidad, fiabilidad y dise\u00f1o ecol\u00f3gico la convierten en la opci\u00f3n preferida de contratistas y operadores de todo el mundo.<\/span><\/p>\n<p>\u00a0<img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4834\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/1-3.jpg\" width=\"1000\" height=\"707\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/1-3.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/1-3-300x212.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/1-3-768x543.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/1-3-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/> <img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4835\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/2-2.jpg\" width=\"1000\" height=\"707\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/2-2.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/2-2-300x212.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/2-2-768x543.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/2-2-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/> <img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4836\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/3-1.jpg\" width=\"1000\" height=\"707\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/3-1.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/3-1-300x212.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/3-1-768x543.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/3-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/> <img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4837\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/4-2.jpg\" width=\"1000\" height=\"707\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/4-2.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/4-2-300x212.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/4-2-768x543.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/4-2-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/> <img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4838\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/5-1.jpg\" width=\"1000\" height=\"707\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/5-1.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/5-1-300x212.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/5-1-768x543.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/5-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/> <img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4839\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/6-3.jpg\" width=\"1000\" height=\"707\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/6-3.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/6-3-300x212.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/6-3-768x543.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/6-3-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/> <img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4840\" src=\"https:\/\/rippa-china.com\/wp-content\/uploads\/2024\/06\/7.jpg\" width=\"1000\" height=\"707\" srcset=\"https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/7.jpg 1000w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/7-300x212.jpg 300w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/7-768x543.jpg 768w, https:\/\/www.rippa-china.com\/wp-content\/uploads\/2024\/06\/7-18x12.jpg 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Product Details: R12-2 ECO Mini excavator by RIPPA Introducing the R12-2 ECO mini excavator, a top-selling model from RIPPA, a renowned brand by Shandong RIPPA\u00a0 Machinery Import &amp; Export Co., Ltd. This robust yet compact excavator is designed to meet the needs of various construction and excavation projects. Key Specifications: Tonnage: 1.2 tons Engine: Kubota [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-4829","post","type-post","status-publish","format-standard","hentry","category-excavator"],"acf":[],"_links":{"self":[{"href":"http:\/\/www.rippa-china.com\/es\/wp-json\/wp\/v2\/posts\/4829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rippa-china.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rippa-china.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rippa-china.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rippa-china.com\/es\/wp-json\/wp\/v2\/comments?post=4829"}],"version-history":[{"count":4,"href":"http:\/\/www.rippa-china.com\/es\/wp-json\/wp\/v2\/posts\/4829\/revisions"}],"predecessor-version":[{"id":7721,"href":"http:\/\/www.rippa-china.com\/es\/wp-json\/wp\/v2\/posts\/4829\/revisions\/7721"}],"wp:attachment":[{"href":"http:\/\/www.rippa-china.com\/es\/wp-json\/wp\/v2\/media?parent=4829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rippa-china.com\/es\/wp-json\/wp\/v2\/categories?post=4829"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rippa-china.com\/es\/wp-json\/wp\/v2\/tags?post=4829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}